{"id":23340,"date":"2023-04-24T18:44:52","date_gmt":"2023-04-24T17:44:52","guid":{"rendered":"https:\/\/www.ipleiria.pt\/esadcr\/?p=23340"},"modified":"2023-06-15T11:49:07","modified_gmt":"2023-06-15T10:49:07","slug":"4-cidade-marconi","status":"publish","type":"post","link":"https:\/\/www.ipleiria.pt\/esadcr\/2023\/04\/24\/4-cidade-marconi\/","title":{"rendered":"4. Cidade Marconi"},"content":{"rendered":"\n<div class=\"wp-container-3 wp-block-columns\">\n<div class=\"wp-container-1 wp-block-column\">\n<div style=\"height:37px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" width=\"720\" height=\"405\" src=\"https:\/\/www.ipleiria.pt\/esadcr\/wp-content\/uploads\/sites\/17\/2023\/04\/4cidademarconi.still_.1.jpg\" alt=\"\" class=\"wp-image-23341\" srcset=\"https:\/\/www.ipleiria.pt\/esadcr\/wp-content\/uploads\/sites\/17\/2023\/04\/4cidademarconi.still_.1.jpg 720w, https:\/\/www.ipleiria.pt\/esadcr\/wp-content\/uploads\/sites\/17\/2023\/04\/4cidademarconi.still_.1-300x169.jpg 300w, https:\/\/www.ipleiria.pt\/esadcr\/wp-content\/uploads\/sites\/17\/2023\/04\/4cidademarconi.still_.1-150x84.jpg 150w, https:\/\/www.ipleiria.pt\/esadcr\/wp-content\/uploads\/sites\/17\/2023\/04\/4cidademarconi.still_.1-390x219.jpg 390w, https:\/\/www.ipleiria.pt\/esadcr\/wp-content\/uploads\/sites\/17\/2023\/04\/4cidademarconi.still_.1-489x275.jpg 489w, https:\/\/www.ipleiria.pt\/esadcr\/wp-content\/uploads\/sites\/17\/2023\/04\/4cidademarconi.still_.1-195x110.jpg 195w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-container-2 wp-block-column\">\n<h2><strong><em>Cidade Marconi<\/em><\/strong><\/h2>\n\n\n\n<h3>Ricardo Moreira<\/h3>\n\n\n\n<h4>17h30<br><strong>Ciclo de Cinema, Explora\u00e7\u00f5es visuais e sonoras da paisagem DocLisboa, Impulso, MASI<\/strong><br>Audit\u00f3rio ep1<\/h4>\n\n\n\n<p>Esta \u00e9 a primeira sess\u00e3o do ciclo de cinema apresentado pelo Doclisboa, em conjunto com o Festival Impulso e o Mestrado em Artes do Som e da Imagem da ESAD.CR. O ciclo ter\u00e1 lugar entre Maio e Dezembro de 2023, e pretende explorar as diferentes declina\u00e7\u00f5es e interpreta\u00e7\u00f5es da paisagem e o seu cruzamento e coexist\u00eancia com o elemento sonoro. Os filmes que comp\u00f5em este programa percorrem espa\u00e7os urbanos e rurais marcados pelas transforma\u00e7\u00f5es do seu tecido social, assim como lugares familiares que pertencem \u00e0s paisagens emocionais, dialogando com as nossas ra\u00edzes mais \u00edntimas.<\/p>\n\n\n\n<p>Em Cidade Marconi, a percep\u00e7\u00e3o da rela\u00e7\u00e3o entre uma m\u00fasica e uma fotografia \u00e9 desconstru\u00edda pelo estudo de uma paisagem. A paisagem de uma colina marcada pelo impasse dos diversos projectos imobili\u00e1rios que pretendem a sua transforma\u00e7\u00e3o.<\/p>\n\n\n\n<p>Trailer: https:\/\/youtu.be\/GV9saDhYht4<\/p>\n\n\n\n<p>O visonamento do filme ser\u00e1 seguido de uma conversa com o realizador, Ricardo Moreira, o programador do Doclisboa, Luca D\u2019Introno, e os professores da ESAD, Diogo Alvim e Pedro Letria.<\/p>\n\n\n\n<p><strong>Ricardo Moreira<\/strong><br>Ricardo Moreira completou o seu primeiro filme em 2018, a longa-metragem Cidade Marconi, que foi estreada e premiada no DocLisboa. O seu filme seguinte, a curtametragem Terraformar, foi feita, em grande parte, a partir de restos do filme anterior. Campo de Fuga, o mais recente trabalho, \u00e9 o seu filme mais curto e puramente experimental at\u00e9 agora.<\/p>\n<\/div>\n<\/div>\n\n\n\n<figure class=\"wp-container-5 wp-block-gallery-4 wp-block-gallery alignfull has-nested-images columns-default is-cropped\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"960\" height=\"640\" data-id=\"24646\"  src=\"https:\/\/www.ipleiria.pt\/esadcr\/wp-content\/uploads\/sites\/17\/2023\/06\/23_05_dia_03_cidade_marconi-6.jpg\" alt=\"\" class=\"wp-image-24646\" srcset=\"https:\/\/www.ipleiria.pt\/esadcr\/wp-content\/uploads\/sites\/17\/2023\/06\/23_05_dia_03_cidade_marconi-6.jpg 960w, https:\/\/www.ipleiria.pt\/esadcr\/wp-content\/uploads\/sites\/17\/2023\/06\/23_05_dia_03_cidade_marconi-6-300x200.jpg 300w, https:\/\/www.ipleiria.pt\/esadcr\/wp-content\/uploads\/sites\/17\/2023\/06\/23_05_dia_03_cidade_marconi-6-150x100.jpg 150w, https:\/\/www.ipleiria.pt\/esadcr\/wp-content\/uploads\/sites\/17\/2023\/06\/23_05_dia_03_cidade_marconi-6-768x512.jpg 768w, https:\/\/www.ipleiria.pt\/esadcr\/wp-content\/uploads\/sites\/17\/2023\/06\/23_05_dia_03_cidade_marconi-6-390x260.jpg 390w, https:\/\/www.ipleiria.pt\/esadcr\/wp-content\/uploads\/sites\/17\/2023\/06\/23_05_dia_03_cidade_marconi-6-810x540.jpg 810w, https:\/\/www.ipleiria.pt\/esadcr\/wp-content\/uploads\/sites\/17\/2023\/06\/23_05_dia_03_cidade_marconi-6-413x275.jpg 413w, https:\/\/www.ipleiria.pt\/esadcr\/wp-content\/uploads\/sites\/17\/2023\/06\/23_05_dia_03_cidade_marconi-6-195x130.jpg 195w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"960\" height=\"640\" data-id=\"24645\"  src=\"https:\/\/www.ipleiria.pt\/esadcr\/wp-content\/uploads\/sites\/17\/2023\/06\/23_05_dia_03_cidade_marconi-10.jpg\" alt=\"\" class=\"wp-image-24645\" srcset=\"https:\/\/www.ipleiria.pt\/esadcr\/wp-content\/uploads\/sites\/17\/2023\/06\/23_05_dia_03_cidade_marconi-10.jpg 960w, https:\/\/www.ipleiria.pt\/esadcr\/wp-content\/uploads\/sites\/17\/2023\/06\/23_05_dia_03_cidade_marconi-10-300x200.jpg 300w, https:\/\/www.ipleiria.pt\/esadcr\/wp-content\/uploads\/sites\/17\/2023\/06\/23_05_dia_03_cidade_marconi-10-150x100.jpg 150w, https:\/\/www.ipleiria.pt\/esadcr\/wp-content\/uploads\/sites\/17\/2023\/06\/23_05_dia_03_cidade_marconi-10-768x512.jpg 768w, https:\/\/www.ipleiria.pt\/esadcr\/wp-content\/uploads\/sites\/17\/2023\/06\/23_05_dia_03_cidade_marconi-10-390x260.jpg 390w, https:\/\/www.ipleiria.pt\/esadcr\/wp-content\/uploads\/sites\/17\/2023\/06\/23_05_dia_03_cidade_marconi-10-810x540.jpg 810w, https:\/\/www.ipleiria.pt\/esadcr\/wp-content\/uploads\/sites\/17\/2023\/06\/23_05_dia_03_cidade_marconi-10-413x275.jpg 413w, https:\/\/www.ipleiria.pt\/esadcr\/wp-content\/uploads\/sites\/17\/2023\/06\/23_05_dia_03_cidade_marconi-10-195x130.jpg 195w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/figure>\n<\/figure>\n\n\n\n<h5 class=\"has-text-align-center\"><a href=\"https:\/\/www.ipleiria.pt\/esadcr\/2023\/04\/21\/exposicao-do-ano-4-maio\/?_thumbnail_id=22908\">&#8211; VOLTAR &#8211; <\/a><\/h5>\n","protected":false},"excerpt":{"rendered":"Cidade Marconi Ricardo Moreira 17h30Ciclo de Cinema, Explora\u00e7\u00f5es visuais e sonoras da paisagem DocLisboa, Impulso, MASIAudit\u00f3rio ep1 Esta \u00e9 a primeira sess\u00e3o do ciclo de cinema apresentado pelo Doclisboa, em conjunto com o Festival Impulso e o Mestrado em Artes do Som e da Imagem da ESAD.CR. O ciclo ter\u00e1 lugar entre Maio e Dezembro [&hellip;]","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"multilingual_post_translation":"","custompostfields_banners":"","custompostfields_post-association_course-gallery":[],"custompostfields_titulo-homepage":"","custompostfields_event-date":"2023-04-24","custompostfields_event-end-date":"2023-04-24","custompostfields_front-page-gallery-thumbnails":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.ipleiria.pt\/esadcr\/wp-json\/wp\/v2\/posts\/23340"}],"collection":[{"href":"https:\/\/www.ipleiria.pt\/esadcr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ipleiria.pt\/esadcr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ipleiria.pt\/esadcr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ipleiria.pt\/esadcr\/wp-json\/wp\/v2\/comments?post=23340"}],"version-history":[{"count":8,"href":"https:\/\/www.ipleiria.pt\/esadcr\/wp-json\/wp\/v2\/posts\/23340\/revisions"}],"predecessor-version":[{"id":24649,"href":"https:\/\/www.ipleiria.pt\/esadcr\/wp-json\/wp\/v2\/posts\/23340\/revisions\/24649"}],"wp:attachment":[{"href":"https:\/\/www.ipleiria.pt\/esadcr\/wp-json\/wp\/v2\/media?parent=23340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ipleiria.pt\/esadcr\/wp-json\/wp\/v2\/categories?post=23340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ipleiria.pt\/esadcr\/wp-json\/wp\/v2\/tags?post=23340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}